{"id":733,"date":"2020-12-17T09:31:46","date_gmt":"2020-12-17T08:31:46","guid":{"rendered":"https:\/\/www2.varmeco.de\/?page_id=733"},"modified":"2026-03-30T12:23:38","modified_gmt":"2026-03-30T10:23:38","slug":"planung","status":"publish","type":"page","link":"https:\/\/varmeco.de\/it\/planung\/","title":{"rendered":"Pianificazione"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"733\" class=\"elementor elementor-733\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0d2faa1 e-flex e-con-boxed e-con e-parent\" data-id=\"0d2faa1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9c19c49 e-flex e-con-boxed e-con e-child\" data-id=\"9c19c49\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9afeb7d elementor-widget elementor-widget-heading\" data-id=\"9afeb7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Dalla richiesta al servizio tecnico<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7d3e5b elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"a7d3e5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ogni investimento sicuro inizia con una consulenza esperta. Vi assistiamo con la nostra gamma di servizi personalizzati, caratterizzati da fiducia, integrit\u00e0 ed esperienza.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7804ed1 elementor-widget elementor-widget-button\" data-id=\"7804ed1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#cta_anfrage\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-down\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiesta di consulenza<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-395fff2 e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"395fff2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-21c991f e-con-full e-flex e-con e-child\" data-id=\"21c991f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6270d70 elementor-widget elementor-widget-heading\" data-id=\"6270d70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Perch\u00e9 varmeco come partner di progettazione?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a205aec elementor-widget elementor-widget-heading\" data-id=\"a205aec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Dal 1983 siamo sinonimo di consulenza affidabile e attenta ai dettagli, concetti innovativi e discussioni tecniche mirate.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-31977ae e-con-full e-grid e-con e-child\" data-id=\"31977ae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-26073f4 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"26073f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-building\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tTutti i tipi di edifici\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tCompetenza per alberghi, industrie, edifici residenziali e pubblici.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b4f992 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"9b4f992\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-certificate\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tOltre 40 anni di esperienza\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDal 1983 siamo sinonimo di consulenza affidabile, attenzione ai dettagli e concetti innovativi.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c87a6c elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"5c87a6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-leaf\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSistemi ottimizzati\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSoluzioni tecnicamente ed economicamente ottimizzate per la massima efficienza.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0368707 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"0368707\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-user-friends\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSupporto olistico\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDall'idea iniziale all'assistenza continua: tutto da un'unica fonte.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fb04246 e-flex e-con-boxed e-con e-parent\" data-id=\"fb04246\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f214c86 elementor-widget elementor-widget-heading\" data-id=\"f214c86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Il nostro processo di pianificazione<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83531d4 elementor-widget elementor-widget-heading\" data-id=\"83531d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Dalla discussione preliminare alla messa in funzione, offriamo soluzioni per tutti gli aspetti della realizzazione del vostro progetto.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc9ec77 uael-timeline-responsive-mobile uael-timeline--center uael-timeline-arrow-center elementor-widget elementor-widget-uael-timeline\" data-id=\"bc9ec77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-timeline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"uael-timeline-wrapper uael-timeline-node\">\n\t\n\t<div class=\"uael-timeline-main\">\n\t\t<div class=\"uael-days\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-ca7de3d uael-timeline-field animate-border out-view\">\n\t\t\t\t\t\t<div class=\"uael-timeline-widget uael-timeline-right\">\n\t\t\t\t\t\t\t<div class=\"uael-timeline-marker\">\n\t\t\t\t\t\t\t\t<span class=\"timeline-icon-new out-view-timeline-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"uael-day-new uael-day-right\">\n\t\t\t\t\t\t\t\t<div class=\"uael-events-new\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-events-inner-new\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-date-hide uael-date-inner\"><div class=\"inner-date-new\"><p >01<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-heading-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"uael-timeline-heading\">Discussione e pianificazione preliminare<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-desc-content\"> <p>Coordinamento congiunto con progettisti, architetti e operatori per registrare tutti i requisiti.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-arrow\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-date-new\">\n\t\t\t\t\t\t\t\t\t<div class=\"uael-date-new\"><div class=\"inner-date-new\"><div >01<\/div><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-6a166eb uael-timeline-field animate-border out-view\">\n\t\t\t\t\t\t<div class=\"uael-timeline-widget uael-timeline-left\">\n\t\t\t\t\t\t\t<div class=\"uael-timeline-marker\">\n\t\t\t\t\t\t\t\t<span class=\"timeline-icon-new out-view-timeline-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"uael-day-new uael-day-left\">\n\t\t\t\t\t\t\t\t<div class=\"uael-events-new\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-events-inner-new\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-date-hide uael-date-inner\"><div class=\"inner-date-new\"><p >02<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-heading-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"uael-timeline-heading\">Concetto di sistema e profili di carico<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-desc-content\"> <p>Creazione di concetti di sistema personalizzati con determinazione dettagliata del profilo di carico.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-arrow\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-date-new\">\n\t\t\t\t\t\t\t\t\t<div class=\"uael-date-new\"><div class=\"inner-date-new\"><div >02<\/div><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-d7ba9ed uael-timeline-field animate-border out-view\">\n\t\t\t\t\t\t<div class=\"uael-timeline-widget uael-timeline-right\">\n\t\t\t\t\t\t\t<div class=\"uael-timeline-marker\">\n\t\t\t\t\t\t\t\t<span class=\"timeline-icon-new out-view-timeline-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"uael-day-new uael-day-right\">\n\t\t\t\t\t\t\t\t<div class=\"uael-events-new\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-events-inner-new\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-date-hide uael-date-inner\"><div class=\"inner-date-new\"><p >03<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-heading-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"uael-timeline-heading\">Simulazione e dimensionamento<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-desc-content\"> <p>Simulazione precisa con il nostro diagramma termico e dimensionamento ottimizzato dei componenti.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-arrow\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-date-new\">\n\t\t\t\t\t\t\t\t\t<div class=\"uael-date-new\"><div class=\"inner-date-new\"><div >03<\/div><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-2b27349 uael-timeline-field animate-border out-view\">\n\t\t\t\t\t\t<div class=\"uael-timeline-widget uael-timeline-left\">\n\t\t\t\t\t\t\t<div class=\"uael-timeline-marker\">\n\t\t\t\t\t\t\t\t<span class=\"timeline-icon-new out-view-timeline-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"uael-day-new uael-day-left\">\n\t\t\t\t\t\t\t\t<div class=\"uael-events-new\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-events-inner-new\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-date-hide uael-date-inner\"><div class=\"inner-date-new\"><p >04<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-heading-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"uael-timeline-heading\">Idraulica e calcolo dei costi<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-desc-content\"> <p>Idraulica del sistema specifica per il progetto e calcoli dei costi personalizzati.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-arrow\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-date-new\">\n\t\t\t\t\t\t\t\t\t<div class=\"uael-date-new\"><div class=\"inner-date-new\"><div >04<\/div><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-f6ec864 uael-timeline-field animate-border out-view\">\n\t\t\t\t\t\t<div class=\"uael-timeline-widget uael-timeline-right\">\n\t\t\t\t\t\t\t<div class=\"uael-timeline-marker\">\n\t\t\t\t\t\t\t\t<span class=\"timeline-icon-new out-view-timeline-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"uael-day-new uael-day-right\">\n\t\t\t\t\t\t\t\t<div class=\"uael-events-new\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-events-inner-new\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-date-hide uael-date-inner\"><div class=\"inner-date-new\"><p >05<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-heading-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"uael-timeline-heading\">Pianificazione e realizzazione dettagliate<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-desc-content\"> <p>Stretta collaborazione nella pianificazione dettagliata e supporto durante la fase di esecuzione.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-arrow\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-date-new\">\n\t\t\t\t\t\t\t\t\t<div class=\"uael-date-new\"><div class=\"inner-date-new\"><div >05<\/div><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-58434d6 uael-timeline-field animate-border out-view\">\n\t\t\t\t\t\t<div class=\"uael-timeline-widget uael-timeline-left\">\n\t\t\t\t\t\t\t<div class=\"uael-timeline-marker\">\n\t\t\t\t\t\t\t\t<span class=\"timeline-icon-new out-view-timeline-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"uael-day-new uael-day-left\">\n\t\t\t\t\t\t\t\t<div class=\"uael-events-new\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-events-inner-new\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-date-hide uael-date-inner\"><div class=\"inner-date-new\"><p >06<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-heading-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"uael-timeline-heading\">Servizio e ulteriore sviluppo<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-desc-content\"> <p>Messa in servizio, assistenza tecnica e scambio continuo di esperienze.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-arrow\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-timeline-date-new\">\n\t\t\t\t\t\t\t\t\t<div class=\"uael-date-new\"><div class=\"inner-date-new\"><div >06<\/div><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"uael-timeline__line\">\n\t\t\t<div class=\"uael-timeline__line__inner\"><\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-802c6fd e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"802c6fd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6cd1ae1 elementor-widget elementor-widget-heading\" data-id=\"6cd1ae1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dal 1983 forniamo una consulenza affidabile:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0449e70 elementor-widget elementor-widget-heading\" data-id=\"0449e70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Il nostro obiettivo comune \u00e8 promuovere la qualit\u00e0 e garantire cos\u00ec il successo globale. Offriamo ai nostri clienti sistemi ottimizzati dal punto di vista tecnico ed economico, dalla discussione preliminare iniziale alla progettazione e alla realizzazione, fino all'assistenza tecnica.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1928e8f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1928e8f7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-59458928\" data-id=\"59458928\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2f30c7 elementor-widget elementor-widget-text-editor\" data-id=\"f2f30c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"Textinhalt\"><strong>La nostra gamma di servizi non si limita alla vendita dei nostri prodotti, ma comprende anche soluzioni per tutti i problemi che si presentano durante la realizzazione:<\/strong><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d0ef594 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d0ef594\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ec79877\" data-id=\"ec79877\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3feb790 elementor-widget elementor-widget-text-editor\" data-id=\"3feb790\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li><div class=\"Textinhalt\">Discussione preliminare\/pianificazione con progettista\/architetto\/operatore<\/div><\/li><li><div class=\"Textinhalt\">Creazione di concetti di sistema<\/div><\/li><li><div class=\"Textinhalt\">Determinazione dei profili di carico<\/div><\/li><li><div class=\"Textinhalt\">Simulazione con il diagramma di calore:<br \/><br \/><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-739 size-full\" src=\"https:\/\/www2.varmeco.de\/wp-content\/uploads\/2020\/12\/Waermeschaubild-02.png\" alt=\"Immagine termica-02\" width=\"484\" height=\"260\" title=\"\" srcset=\"https:\/\/varmeco.de\/wp-content\/uploads\/2020\/12\/Waermeschaubild-02.png 484w, https:\/\/varmeco.de\/wp-content\/uploads\/2020\/12\/Waermeschaubild-02-300x161.png 300w\" sizes=\"(max-width: 484px) 100vw, 484px\" \/><\/div><\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1e9b31b\" data-id=\"1e9b31b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b596053 elementor-widget elementor-widget-text-editor\" data-id=\"b596053\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"Textinhalt\">5. creazione dell'impianto idraulico specifico della propriet\u00e0 (schemi, ecc.)<\/div><div class=\"Textinhalt\">6. dimensionamento dei componenti del sistema\/selezione<\/div><div class=\"Textinhalt\">7. calcolo dei costi individuali<\/div><div class=\"Textinhalt\">8. Pianificazione dettagliata in collaborazione con il pianificatore\/operatore.<\/div><div class=\"Textinhalt\">9a fase di esecuzione: supervisione degli installatori\/artigiani<\/div><div class=\"Textinhalt\">10. messa in servizio<\/div><div class=\"Textinhalt\">11. servizio: Manutenzione, assistenza tecnica ai clienti<\/div><div class=\"Textinhalt\">12. scambio di esperienze con il cliente -&gt; ulteriore sviluppo<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-d49ea37 e-flex e-con-boxed e-con e-parent\" data-id=\"d49ea37\" data-element_type=\"container\" data-e-type=\"container\" id=\"cta_anfrage\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a423b18 elementor-widget elementor-widget-heading\" data-id=\"a423b18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Iniziate subito a pianificare il vostro progetto<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21f5c97 elementor-widget__width-initial text-zentriert elementor-widget elementor-widget-text-editor\" data-id=\"21f5c97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">\n  Contattate i nostri esperti per una prima consulenza non vincolante.<br>\n  Insieme svilupperemo la soluzione ottimale per il vostro progetto.\n<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba1a09d elementor-widget elementor-widget-button\" data-id=\"ba1a09d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/varmeco.de\/it\/zentrale\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiedi subito una consulenza<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2fc8b24 e-con-full e-flex e-con e-parent\" data-id=\"2fc8b24\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-848e8ce e-con-full e-flex e-con e-child\" data-id=\"848e8ce\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9198117 elementor-widget elementor-widget-heading\" data-id=\"9198117\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Domande frequenti<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-37c6a6e e-flex e-con-boxed e-con e-child\" data-id=\"37c6a6e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5d07bd94 align-at-left elementor-widget elementor-widget-uael-faq\" data-id=\"5d07bd94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"uael-faq.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<div id='uael-faq-wrapper-156' class=\"uael-faq-wrapper\">\n\t\t\t\t<div class=\"uael-faq-container uael-faq-layout-accordion\" data-layout=\"accordion\" >\n\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-2d3b487\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<h3 class=\"uael-question-2d3b487 uael-question-span\" tabindex=\"0\" id=\"uael-faq-1-6a560ac6cfc45\"> Quali servizi offre varmeco per la progettazione di impianti di riscaldamento? <\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>varmeco fornisce un supporto completo per i progetti, dall'idea iniziale all'assistenza continua. Questo include discussioni e pianificazioni preliminari, la creazione di concetti di sistema, simulazioni di profili di carico con diagrammi di calore, nonch\u00e9 la pianificazione di impianti idraulici, controllori e componenti specifici per il progetto.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-d3259b5\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<h3 class=\"uael-question-d3259b5 uael-question-span\" tabindex=\"0\" id=\"uael-faq-2-6a560ac6cfce6\">In che modo varmeco supporta il dimensionamento di un sistema?<\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>Sulla base dei profili di carico coordinati e della situazione individuale dell'edificio, varmeco sviluppa esattamente il sistema idraulico adatto. Le dimensioni dei serbatoi di stoccaggio, la tecnologia dell'acqua dolce, le stazioni di trasferimento del calore e i sistemi di controllo sono ottimizzati dal punto di vista tecnico ed economico.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-71ee202\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<h3 class=\"uael-question-71ee202 uael-question-span\" tabindex=\"0\" id=\"uael-faq-3-6a560ac6cfd57\">Per quali tipi di edifici varmeco offre supporto alla progettazione?<\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>La gamma di servizi si estende dalla tecnologia dell'acqua dolce in piccole case monofamiliari ai controllori di sistema in edifici pubblici e alle soluzioni di sistema altamente complesse per applicazioni industriali. Grazie a strumenti di pianificazione flessibili e a un'esperienza pluriennale, \u00e8 possibile pianificare in modo efficiente sia i piccoli progetti che i complessi sistemi su larga scala.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-4e0db92\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<h3 class=\"uael-question-4e0db92 uael-question-span\" tabindex=\"0\" id=\"uael-faq-4-6a560ac6cfdd9\">Che ruolo hanno gli strumenti di pianificazione personalizzati per i prodotti varmeco nello sviluppo del progetto?.<\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>Un software appositamente adattato ai prodotti varmeco consente simulazioni precise dei flussi di calore, la creazione di diagrammi termici e il calcolo automatico dei componenti idraulici. Ci\u00f2 rende i sistemi trasparenti, comprensibili e ottimizzati.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"uael-accordion-1c6ff01\" class=\"uael-faq-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t\t<div class= \"uael-accordion-title\" aria-expanded=\"false\" role=\"tab\">\n\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon uael-accordion-icon-left\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"uael-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<h3 class=\"uael-question-1c6ff01 uael-question-span\" tabindex=\"0\" id=\"uael-faq-5-6a560ac6cfe47\">Quali servizi offriamo durante la fase di realizzazione?<\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"uael-accordion-content\" role=\"tabpanel\">\n\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t<span><p>Durante l'implementazione, varmeco supporta gli installatori e gli artigiani, assiste nelle questioni interne e trasversali, accompagna la messa in servizio e, se necessario, offre un servizio completo che comprende la manutenzione e l'assistenza ai clienti, nonch\u00e9 l'ottimizzazione del sistema via web per garantire un funzionamento sicuro e regolare del sistema.<\/p><\/span>\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Von der Anfrage bis zum technischen Service Jede gesicherte Investition beginnt mit kompetenter Beratung. Wir begleiten Sie mit unserem individuellen [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"folder":[],"class_list":["post-733","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/varmeco.de\/it\/wp-json\/wp\/v2\/pages\/733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/varmeco.de\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/varmeco.de\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/varmeco.de\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/varmeco.de\/it\/wp-json\/wp\/v2\/comments?post=733"}],"version-history":[{"count":59,"href":"https:\/\/varmeco.de\/it\/wp-json\/wp\/v2\/pages\/733\/revisions"}],"predecessor-version":[{"id":25007,"href":"https:\/\/varmeco.de\/it\/wp-json\/wp\/v2\/pages\/733\/revisions\/25007"}],"wp:attachment":[{"href":"https:\/\/varmeco.de\/it\/wp-json\/wp\/v2\/media?parent=733"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/varmeco.de\/it\/wp-json\/wp\/v2\/folder?post=733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}